{"id":46675,"date":"2025-03-24T13:48:05","date_gmt":"2025-03-24T10:48:05","guid":{"rendered":"https:\/\/vitalmutfak.com\/urun\/griglia-a-pavimento-tipo-s1-con-scarico-inferiore-e-sifone-centrale-750x200\/"},"modified":"2026-01-05T16:40:35","modified_gmt":"2026-01-05T13:40:35","slug":"griglia-a-pavimento-tipo-s1-con-scarico-inferiore-e-sifone-centrale-750x200","status":"publish","type":"urun","link":"https:\/\/vitalmutfak.com\/it\/urun\/griglia-a-pavimento-tipo-s1-con-scarico-inferiore-e-sifone-centrale-750x200\/","title":{"rendered":"Griglia a pavimento tipo S1 con scarico inferiore e sifone centrale (750&#215;200)"},"content":{"rendered":"<p>&#8211; Tutti realizzati in acciaio inox AIS 18\/8. I giunti delle vasche sono saldati con il metodo dell&#8217;argon e sono a prova di perdite. Ci sono orecchie speciali che permettono di fissare le pentole al cemento. Sono presenti alveoli dentellati rimovibili, distanziati di 25&#215;25 mm, che impediscono lo scivolamento. Il sifone saldato alla vaschetta di scarico evita la formazione di cattivi odori. Il sifone \u00e8 dotato di un filtro che impedisce il passaggio dei solidi.     <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8211; Tutti realizzati in acciaio inox AIS 18\/8. I giunti delle vasche sono saldati con il metodo dell&#8217;argon e sono a prova di perdite. Ci sono orecchie speciali che permettono di fissare le pentole al cemento. Sono presenti alveoli dentellati rimovibili, distanziati di 25&#215;25 mm, che impediscono lo scivolamento. Il sifone saldato alla vaschetta di [&hellip;]<\/p>\n","protected":false},"featured_media":0,"parent":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"urun-kategori":[670],"class_list":["post-46675","urun","type-urun","status-publish","hentry","urun-kategori-griglie-per-pavimenti"],"acf":[],"_links":{"self":[{"href":"https:\/\/vitalmutfak.com\/it\/wp-json\/wp\/v2\/urun\/46675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vitalmutfak.com\/it\/wp-json\/wp\/v2\/urun"}],"about":[{"href":"https:\/\/vitalmutfak.com\/it\/wp-json\/wp\/v2\/types\/urun"}],"version-history":[{"count":1,"href":"https:\/\/vitalmutfak.com\/it\/wp-json\/wp\/v2\/urun\/46675\/revisions"}],"predecessor-version":[{"id":59093,"href":"https:\/\/vitalmutfak.com\/it\/wp-json\/wp\/v2\/urun\/46675\/revisions\/59093"}],"wp:attachment":[{"href":"https:\/\/vitalmutfak.com\/it\/wp-json\/wp\/v2\/media?parent=46675"}],"wp:term":[{"taxonomy":"urun-kategori","embeddable":true,"href":"https:\/\/vitalmutfak.com\/it\/wp-json\/wp\/v2\/urun-kategori?post=46675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}